{"id":694,"date":"2007-02-26T13:25:55","date_gmt":"2007-02-26T12:25:55","guid":{"rendered":"http:\/\/www.roninarts.de\/wp\/?p=694"},"modified":"2007-02-26T13:25:55","modified_gmt":"2007-02-26T12:25:55","slug":"schoen","status":"publish","type":"post","link":"http:\/\/www.roninarts.de\/wp\/2007\/02\/26\/schoen\/","title":{"rendered":"sch\u00f6ne oskarnacht"},"content":{"rendered":"<p>popcorn, bionade und kippen kaltgestellt! its oskar-time! <\/p>\n<p>pro7 ihr seid scheisse. a) keine orginalwerbung belassen, b) schwachsinnige moderatoren der &#8222;red carpet show&#8220; c) keine &#8222;moderation\/kommentar\/untertitel&#8220; der eigentlich oskarshow, das ist sehr schade! warum nicht das ganze von einem oder mehreren filmschaffenden kommentiern lassen, quasi wie eine sportveranstaltung?<\/p>\n<p>ersteinmal:der deutschsprachige beitrag <a href=\"http:\/\/de.wikipedia.org\/wiki\/Das_Leben_der_Anderen\">&#8222;das leben der anderen&#8220;<\/a> hat den oskar bekommen. herzlichen gl\u00fcckwunsch. der traum von vielen. und das mit einem erstlingswerk. wow.<\/p>\n<p>spannend war aber auch Nicole Kidman im roten Abendkleid (unglaublich!), Penelope Cruz wie immer mit wunderbarem Akzent (charming!) und ein verdammt smarter George Clooney (w\u00e4re ich schwul, er w\u00e4r mein posterboy). Jack Nicholson im publikum mit glatze, bleich und aufgedunsen gesicht, sah richtig fies aus! und hatte gut lachen, hat ja schon 3 oskars \ud83d\ude09 <\/p>\n<p>sehr gefreut habe ich mich \u00fcber den oskar f\u00fcr <a href=\"http:\/\/en.wikipedia.org\/wiki\/Little_Miss_Sunshine\">&#8222;little miss sunshine&#8220;<\/a> (toller film! so positiv und irgendie indie-liebenswert) und die grosse anzahl f\u00fcr <a href=\"http:\/\/en.wikipedia.org\/wiki\/Pan%27s_labyrinth\">&#8222;pans labyrinth&#8220; <\/a>(f\u00fcr nerds von nerds). komisch das <a href=\"http:\/\/en.wikipedia.org\/wiki\/Babel_%28film%29\">&#8222;babel&#8220; <\/a>(komplett \u00fcbersch\u00e4tzt IMHO, aber trotzdem sehr interessant) so leer ausging (schade!), obwohl es ja einen oskar f\u00fcr den score gab (und der ist auch richtig richtig gut!)<\/p>\n<p>das &#8222;de caprio&#8220; den oskar nicht bekommen hat, ist auch gut. gebt dem kerl noch 10 jahre und er wird richtig aufbl\u00fchen. <a href=\"http:\/\/en.wikipedia.org\/wiki\/The_Departed\">&#8222;the departed&#8220; <\/a>, mmh, weis nicht, solider film, aber das ganze dann doch nur ein remake (rip-off?) von <a href=\"http:\/\/en.wikipedia.org\/wiki\/Infernal_Affairs\">&#8222;infernal affairs&#8220;<\/a> ist, wird irgendwie immer sch\u00f6n verschwiegen. <\/p>\n<p>das <a href=\"http:\/\/en.wikipedia.org\/wiki\/The_Departed\">Martin Scorsese<\/a> (Mean Streets, Taxi Driver,  Raging Bull, The Color of Money,the Last Temptation of Christ, Goodfellas, Casino etc )den oskar erh\u00e4lt ist jawohl mehr als \u00fcberf\u00e4llig. h\u00fcstel! <\/p>\n<p>grossartig auch das die &#8222;drei amigos&#8220;; (Alfonso Cuar\u00f3n (children of men), Alejandro Gonz\u00e1lez I\u00f1\u00e1rritu (babel) und del Torro (pans labyrinth) gemeinsam am Oskarabend da waren, um ihre Filme zu repr\u00e4sentieren \u2013 die drei sind sehr gut befreundet &#038; haben schon oft miteinander\/untereinander gearbeitet \u2013 eine grossartige leistung f\u00fcr das mexikanische kino &#038; ein bweis f\u00fcr den wert von freundschaften.<\/p>\n<p>puuuh, und dann war ich so gegen 5:30 im arsch und bin pennen gegangen  \u2026<\/p>\n","protected":false},"excerpt":{"rendered":"<p>popcorn, bionade und kippen kaltgestellt! its oskar-time! pro7 ihr seid scheisse. a) keine orginalwerbung belassen, b) schwachsinnige moderatoren der &#8222;red carpet show&#8220; c) keine &#8222;moderation\/kommentar\/untertitel&#8220; der eigentlich oskarshow, das ist sehr schade! warum nicht das ganze von einem oder mehreren filmschaffenden kommentiern lassen, quasi wie eine sportveranstaltung? ersteinmal:der deutschsprachige beitrag &#8222;das leben der anderen&#8220; hat &hellip; <\/p>\n<p class=\"link-more\"><a href=\"http:\/\/www.roninarts.de\/wp\/2007\/02\/26\/schoen\/\" class=\"more-link\"><span class=\"screen-reader-text\">\u201esch\u00f6ne oskarnacht\u201c <\/span>weiterlesen<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[9],"tags":[],"class_list":["post-694","post","type-post","status-publish","format-standard","hentry","category-uncategorized","entry"],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/s8thp-schoen","jetpack-related-posts":[{"id":2415,"url":"http:\/\/www.roninarts.de\/wp\/2014\/10\/09\/alle-jahre-wieder-kommt-das\/","url_meta":{"origin":694,"position":0},"title":"alle jahre wieder kommt \u2026","author":"danielkoening","date":"9. Oktober 2014","format":false,"excerpt":"gerade meinen 39. Geburtstag \u00fcberlebt, festgestellt, das leider schon wieder zu lange, nicht hier reingeschrieben. gestern war so gesehen ein guter\u00a0Tag, kein Superlativ, wie vor 10 Jahren in Australien, keine Freakshow, wie vor 5 Jahren auf ner Dope Farm in Kalifornien, also eigentlich ziemlich langweilig und bieder, aber hey OK!\u2026","rel":"","context":"In &quot;d\u00fcsseldorf&quot;","block_context":{"text":"d\u00fcsseldorf","link":"http:\/\/www.roninarts.de\/wp\/category\/dusseldorf\/"},"img":{"alt_text":"tumblr_m0s2n4lgbD1r8pjnro1_500","src":"https:\/\/i0.wp.com\/www.roninarts.de\/wp\/wp-content\/uploads\/2014\/10\/tumblr_m0s2n4lgbD1r8pjnro1_500-300x201.gif?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":12,"url":"http:\/\/www.roninarts.de\/wp\/2005\/12\/07\/reflexionen-uber-hier-und-da\/","url_meta":{"origin":694,"position":1},"title":"reflexionen \u00fcber hier und da","author":"dan","date":"7. Dezember 2005","format":false,"excerpt":"vom n\u00e4chtlichen email-wechsel zum schreibenden selbstgespr\u00e4che. where is my mind? trotz der vielen antworten der letzten monate oder eben gerade deswegen; so viele fragen an das leben und an mich und an andere. immer noch. mehr denn je. >> mensch, daniel, mach schnell diplom, da musst du durch, >> und\u2026","rel":"","context":"\u00c4hnlicher Beitrag","block_context":{"text":"\u00c4hnlicher Beitrag","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":3062,"url":"http:\/\/www.roninarts.de\/wp\/2015\/06\/01\/festival-der-bierkulturen-koeln-2015\/","url_meta":{"origin":694,"position":2},"title":"Festival der Bierkulturen, K\u00f6ln, 2015","author":"danielkoening","date":"1. Juni 2015","format":false,"excerpt":"Ne wat war dat wieder sch\u00f6n! Selbst oder gerade nach dem Megafestival in Copenhagen und den andauernden Superlativen in Berlin und Hamburg freut ich mich, das auch dieses Jahr, das K\u00f6lner Festival wieder so grossartig war. Ja, gerade Samstag war es sehr voll, Craft Beer wird immer dicker in Deutschland,\u2026","rel":"","context":"\u00c4hnlicher Beitrag","block_context":{"text":"\u00c4hnlicher Beitrag","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":13,"url":"http:\/\/www.roninarts.de\/wp\/2005\/12\/07\/13\/","url_meta":{"origin":694,"position":3},"title":"&#8222;hinchinbrooke island&#8220; und der &#8222;thorsborne trail&#8220;","author":"dan","date":"7. Dezember 2005","format":false,"excerpt":"dieses st\u00fcck text m\u00f6chte ich dann noch niemandem vorenthalten, bzw . ab ins web zur archivierung. gammelte auf meiner festpladde rum \u2026 gerade aktuell ! crocs signs!irgendwie gruselig! schliesslich watr ich alleine da und vorallem in lttle ramsey bay! prolog (september 2005, ostk\u00fcste cairns) nachdem ich \"good old liam\" silkes\u2026","rel":"","context":"Mit 2 Kommentaren","block_context":{"text":"Mit 2 Kommentaren","link":"http:\/\/www.roninarts.de\/wp\/2005\/12\/07\/13\/#comments"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2900,"url":"http:\/\/www.roninarts.de\/wp\/2015\/04\/04\/mit-entsetzen-musste-ich-gerade\/","url_meta":{"origin":694,"position":4},"title":"Mit Entsetzen musste ich gerade","author":"danielkoening","date":"4. April 2015","format":false,"excerpt":"feststellen, das mein erster 21k Lauf genau vor einem Jahr war. Genau heute ist gerade in Benrath wieder der sch\u00f6ne Benrather Volkslauf. Ich kann die Strecke sehr empfehlen f\u00fcr den ersten Lauf, bzw. wunderbar flach, \u00fcber Waldboden durch den Wald und um den See. Mit gro\u00dfer Freude denke ich an\u2026","rel":"","context":"In &quot;recap&quot;","block_context":{"text":"recap","link":"http:\/\/www.roninarts.de\/wp\/category\/uncategorized\/recap\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":929,"url":"http:\/\/www.roninarts.de\/wp\/2007\/08\/26\/open-source-festival-2007-ohne-regen-mit-sonne-und-aversionen\/","url_meta":{"origin":694,"position":5},"title":"open-source-festival 2007, ohne regen, mit sonne und aversionen","author":"dan","date":"26. August 2007","format":false,"excerpt":"bis auf ein sch\u00f6nes gespr\u00e4ch und die anwesendheit einer charmanten dame LEIDER [f\u00fcr MICH] absolut unbedeutend. die musik, ergo die bands waren in keinsterweise relevant [f\u00fcr MICH], inwiefern erlend o. und band noch durch bonusauftritte in der \"crowd\" gewannen. der ganze \"abendteil\" war nur peinlich und absolut sinnfrei. weder musikstil\u2026","rel":"","context":"Mit 11 Kommentaren","block_context":{"text":"Mit 11 Kommentaren","link":"http:\/\/www.roninarts.de\/wp\/2007\/08\/26\/open-source-festival-2007-ohne-regen-mit-sonne-und-aversionen\/#comments"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"http:\/\/www.roninarts.de\/wp\/wp-json\/wp\/v2\/posts\/694","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.roninarts.de\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.roninarts.de\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.roninarts.de\/wp\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.roninarts.de\/wp\/wp-json\/wp\/v2\/comments?post=694"}],"version-history":[{"count":0,"href":"http:\/\/www.roninarts.de\/wp\/wp-json\/wp\/v2\/posts\/694\/revisions"}],"wp:attachment":[{"href":"http:\/\/www.roninarts.de\/wp\/wp-json\/wp\/v2\/media?parent=694"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.roninarts.de\/wp\/wp-json\/wp\/v2\/categories?post=694"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.roninarts.de\/wp\/wp-json\/wp\/v2\/tags?post=694"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}